{"id":2350,"date":"2018-08-06T15:01:41","date_gmt":"2018-08-06T12:01:41","guid":{"rendered":"https:\/\/www.uksetehas.ee\/toode\/fancy-v5-glass\/"},"modified":"2024-01-03T15:36:40","modified_gmt":"2024-01-03T13:36:40","slug":"fancy-v5-glass","status":"publish","type":"product","link":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/","title":{"rendered":"Fancy V5 Glass"},"content":{"rendered":"","protected":false},"excerpt":{"rendered":"","protected":false},"featured_media":0,"template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[95,162],"product_tag":[],"class_list":{"0":"post-2350","1":"product","2":"type-product","3":"status-publish","5":"product_cat-doors","6":"product_cat-interior-massive-doors","8":"first","9":"outofstock","10":"shipping-taxable","11":"purchasable","12":"product-type-simple"},"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Fancy V5 Glass - Haapsalu Uksetehas<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Fancy V5 Glass - Haapsalu Uksetehas\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/\" \/>\n<meta property=\"og:site_name\" content=\"Haapsalu Uksetehas\" \/>\n<meta property=\"article:modified_time\" content=\"2024-01-03T13:36:40+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.uksetehas.ee\\\/en\\\/tooted\\\/fancy-v5-glass\\\/\",\"url\":\"https:\\\/\\\/www.uksetehas.ee\\\/en\\\/tooted\\\/fancy-v5-glass\\\/\",\"name\":\"Fancy V5 Glass - Haapsalu Uksetehas\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.uksetehas.ee\\\/#website\"},\"datePublished\":\"2018-08-06T12:01:41+00:00\",\"dateModified\":\"2024-01-03T13:36:40+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.uksetehas.ee\\\/en\\\/tooted\\\/fancy-v5-glass\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.uksetehas.ee\\\/en\\\/tooted\\\/fancy-v5-glass\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.uksetehas.ee\\\/en\\\/tooted\\\/fancy-v5-glass\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.uksetehas.ee\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Fancy V5 Glass\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.uksetehas.ee\\\/#website\",\"url\":\"https:\\\/\\\/www.uksetehas.ee\\\/\",\"name\":\"Haapsalu Uksetehas\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.uksetehas.ee\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Fancy V5 Glass - Haapsalu Uksetehas","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/","og_locale":"en_US","og_type":"article","og_title":"Fancy V5 Glass - Haapsalu Uksetehas","og_url":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/","og_site_name":"Haapsalu Uksetehas","article_modified_time":"2024-01-03T13:36:40+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/","url":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/","name":"Fancy V5 Glass - Haapsalu Uksetehas","isPartOf":{"@id":"https:\/\/www.uksetehas.ee\/#website"},"datePublished":"2018-08-06T12:01:41+00:00","dateModified":"2024-01-03T13:36:40+00:00","breadcrumb":{"@id":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.uksetehas.ee\/en\/tooted\/fancy-v5-glass\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.uksetehas.ee\/"},{"@type":"ListItem","position":2,"name":"Fancy V5 Glass"}]},{"@type":"WebSite","@id":"https:\/\/www.uksetehas.ee\/#website","url":"https:\/\/www.uksetehas.ee\/","name":"Haapsalu Uksetehas","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.uksetehas.ee\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/product\/2350","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:attachment":[{"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/media?parent=2350"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/product_brand?post=2350"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/product_cat?post=2350"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/www.uksetehas.ee\/en\/wp-json\/wp\/v2\/product_tag?post=2350"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}